{"id":1001,"date":"2021-01-01T23:41:15","date_gmt":"2021-01-01T22:41:15","guid":{"rendered":"https:\/\/qualitypush.com\/w\/2021\/01\/01\/was-ich-gegen-stress-tue\/"},"modified":"2021-01-15T15:33:03","modified_gmt":"2021-01-15T14:33:03","slug":"was-ich-gegen-stress-tue","status":"publish","type":"post","link":"https:\/\/qualitypush.com\/w\/2021\/01\/01\/was-ich-gegen-stress-tue\/","title":{"rendered":"Was ich gegen Stress tue"},"content":{"rendered":"\n<p><strong>In einem sch\u00f6nen kleinen Artikel beschreibt <\/strong><strong><a href=\"https:\/\/www.spektrum.de\/news\/mit-der-richtigen-atmung-und-weitem-blick-stress-abbauen\/1813064\" target=\"_blank\" rel=\"noreferrer noopener\">Spektrum der Wissenschaft, wie Atmung und Blickwinkel den Stresspegel direkt senken k\u00f6nnen<\/a><\/strong><strong>. Ich liebe diese beiden kleinen Methoden und wende sie oft an, auch unbewusst. Die beiden Methoden und was ich sonst noch gegen Stress unternehme (au\u00dfer Sport, ein Bad nehmen und Meditation oder \u00e4hnliche bekannte Dinge), m\u00f6chte ich hier teilen.<\/strong><\/p>\n\n\n\n<p>1. Stresspegel senken durch weitere Perspektive: daf\u00fcr weitet man den eigenen Blick auf &#8222;16:9&#8220; <strong>Panoramaperspektive<\/strong>. Zum Beispiel, indem man auf den Horizont schaut. Das dimmt den Stressmodus im Gehirn direkt herunter. Wird Optischer Fluss genannt. Mehr dazu im Artikel.<\/p>\n\n\n\n<p>2. Atmungsseitig empfiehlt die Wissenschaft sogenannte <strong>physiologische Seufzer<\/strong> auszusto\u00dfen. Das sind Seufzer, bei denen man doppelt ein- und dann kr\u00e4ftig ausatmet. Hierdurch werden das Herz und das Gehirn beruhigt. Hat was mit CO2 zu tun. Mehr dazu im Artikel.<\/p>\n\n\n\n<!--more-->\n\n\n\n<p>Meine eigenen Tipps gehen Stress:<\/p>\n\n\n\n<ul class=\"wp-block-list\"><li><strong>Einsschlafprobleme, weil was Wichtiges ansteht oder ein richtig fieser Tag hinter Dir liegt?<\/strong> Nicht \u00fcberfressen, dann spazieren. Und im Bett folgende \u00dcbung: kr\u00e4ftig einatmen, m\u00f6glichst lange in einem konstantem Strom ausatmen. Wichtig ist, dass du den Atemstrom am Gaumen entlangreiben l\u00e4sst, ich h\u00f6re innerlich richtiggehendes Rauschen. Ich lasse somit sehr wenig Luft passieren. Konzentrier Dich auf diesen Strom. Bei mir dauert (ich habe es gerade eben gemessen) so ein Ausstrom-Zug ca. 50 Sekunden. So langsam muss das sein. Ich Schlaf dabei immer ein.<\/li><li><strong>Eine Entscheidung lastet auf Dir?<\/strong> Wenn mal wieder das Gewicht der ganzen Welt auf mir zu lasten scheint, schaue ich mir gern den Sternenhimmel an und \u00fcberlege, wie super unwichtig wir in Relation sind. Pillepalle, alles pillepalle. Im Vergleich zumindest.<\/li><li><strong>Konfrontationen setzen Dir zu? <\/strong>Mein Puls geht schnell hoch, wenn mir jemand l\u00e4stig gegen\u00fcber tritt. Ich bleibe nicht gelassen, zumindest nicht per se. Was ich mache, um trotzdem ziemlich souver\u00e4n wirken zu k\u00f6nnen: ich schalte in den Kameramodus. Ich betrachte die ganze Situation einfach von au\u00dfen und  interessiere mich f\u00fcr die Interaktion zwischen dem Anderen und mir.<\/li><li><strong>Alles w\u00e4chst dir \u00fcber den Kopf?<\/strong> Manchmal hat man zu viel auf dem Zettel. Man kriegts nicht hin. Aber weil man Anderen seine Zusage gegeben hat, kommt Stress auf. In solchen  Situationen greife ich auf g\u00e4ngige Methoden wie das Eisenhowerprinzip zur\u00fcck, vor allem aber bespreche ich mich viel mit au\u00dfenstehenden Vertrauten. Dies hilft mir oft, ein paar B\u00e4ume aus dem Wald zu entfernen, um dann wieder durchblicken zu k\u00f6nnen.<\/li><\/ul>\n\n\n\n<p>Ausreichend Schlaf ist grunds\u00e4tzlich wichtig, um stressresistent zu sein. Daher hau ich mich jetzt hin. Gute Nacht.<\/p>\n","protected":false},"excerpt":{"rendered":"<p>In einem sch\u00f6nen kleinen Artikel beschreibt Spektrum der Wissenschaft, wie Atmung und Blickwinkel den Stresspegel direkt senken k\u00f6nnen. Ich liebe diese beiden kleinen Methoden und wende sie oft an, auch unbewusst. Die beiden Methoden und was ich sonst noch gegen Stress unternehme (au\u00dfer Sport, ein Bad nehmen und Meditation oder \u00e4hnliche bekannte Dinge), m\u00f6chte ich &hellip; <\/p>\n<p class=\"link-more\"><a href=\"https:\/\/qualitypush.com\/w\/2021\/01\/01\/was-ich-gegen-stress-tue\/\" class=\"more-link\"><span class=\"screen-reader-text\">\u201eWas ich gegen Stress tue\u201c <\/span>weiterlesen<\/a><\/p>\n","protected":false},"author":1,"featured_media":0,"comment_status":"open","ping_status":"open","sticky":false,"template":"","format":"standard","meta":{"jetpack_post_was_ever_published":false,"_jetpack_newsletter_access":"","_jetpack_dont_email_post_to_subs":false,"_jetpack_newsletter_tier_id":0,"_jetpack_memberships_contains_paywalled_content":false,"_jetpack_memberships_contains_paid_content":false,"footnotes":"","jetpack_publicize_message":"","jetpack_publicize_feature_enabled":true,"jetpack_social_post_already_shared":true,"jetpack_social_options":{"image_generator_settings":{"template":"highway","default_image_id":0,"font":"","enabled":false},"version":2}},"categories":[1],"tags":[217,216,215],"class_list":["post-1001","post","type-post","status-publish","format-standard","hentry","category-uncategorized","tag-atmung","tag-optischer-fluss","tag-stressresistenz"],"jetpack_publicize_connections":[],"jetpack_featured_media_url":"","jetpack-related-posts":[{"id":938,"url":"https:\/\/qualitypush.com\/w\/2020\/11\/29\/serie-denkfehler-im-job-6-cue-dependent-forgetting-memory\/","url_meta":{"origin":1001,"position":0},"title":"Serie Denkfehler im Job #6 Cue-Dependent Forgetting \/ Memory","author":"Patrick","date":"29. November 2020","format":false,"excerpt":"\"Erinnern geht nicht immer per Knopfdruck\" Such mal den Knopf am Kopf, der Suchergebnisse f\u00fcr Erinnerungen ausl\u00f6st. Die meisten werden wissen, dass unser Gehirn sich vor allem dann gerne Dinge merkt, wenn die Erinnerung an etwas Auff\u00e4lliges oder an den Kontext gekn\u00fcpft werden kann, in dem gelernt wurde. 1975 sollten\u2026","rel":"","context":"In &quot;Serie: Denkfehler im Job&quot;","block_context":{"text":"Serie: Denkfehler im Job","link":"https:\/\/qualitypush.com\/w\/category\/serie_denkfehler_im_job\/"},"img":{"alt_text":"","src":"https:\/\/i0.wp.com\/qualitypush.com\/w\/wp-content\/uploads\/2020\/11\/Screenshot_20201129-200926_SamsungNotes.jpg?resize=350%2C200&ssl=1","width":350,"height":200,"srcset":"https:\/\/i0.wp.com\/qualitypush.com\/w\/wp-content\/uploads\/2020\/11\/Screenshot_20201129-200926_SamsungNotes.jpg?resize=350%2C200&ssl=1 1x, https:\/\/i0.wp.com\/qualitypush.com\/w\/wp-content\/uploads\/2020\/11\/Screenshot_20201129-200926_SamsungNotes.jpg?resize=525%2C300&ssl=1 1.5x, https:\/\/i0.wp.com\/qualitypush.com\/w\/wp-content\/uploads\/2020\/11\/Screenshot_20201129-200926_SamsungNotes.jpg?resize=700%2C400&ssl=1 2x"},"classes":[]},{"id":1451,"url":"https:\/\/qualitypush.com\/w\/2022\/06\/30\/moderierende-fuehrung-moderations-methoden-sind-nur-hilfestellungen-es-geht-eigentlich-auch-ohne\/","url_meta":{"origin":1001,"position":1},"title":"Moderierende F\u00fchrung: Moderations-Methoden sind nur Hilfestellungen. Es geht eigentlich auch ohne!","author":"Patrick","date":"30. Juni 2022","format":false,"excerpt":"Nach einigen Jahren als Moderator fiel mir auf (ja, ich habe eine lange Leitung), dass Workshop-Methoden in der Regel alle dasselbe tun: Aktivieren Fokussieren Sortieren Egal, ob eine SWOT, ein Value Proposition Canvas oder die 4L-Retro: Es geht immer darum, die Teilnehmer zum Mitmachen einzuladen sie auf bestimmte Fragestellungen hinzulenken\u2026","rel":"","context":"In &quot;Serie: Moderierende F\u00fchrung&quot;","block_context":{"text":"Serie: Moderierende F\u00fchrung","link":"https:\/\/qualitypush.com\/w\/category\/serie_moderierende_fuehrung\/"},"img":{"alt_text":"","src":"","width":0,"height":0},"classes":[]},{"id":1739,"url":"https:\/\/qualitypush.com\/w\/2025\/01\/15\/das-erbe-der-westlichen-welt\/","url_meta":{"origin":1001,"position":2},"title":"Das Erbe der westlichen Welt","author":"Patrick","date":"15. Januar 2025","format":false,"excerpt":"Jede gro\u00dfe Kultur geht einmal unter. Auch die Westliche Welt. Und es mehren sich Anzeichen, dass wir den Zenit nicht unbedingt vor uns haben. Ich empfinde das nicht als Bedrohung, schon gar nicht individuell, da es sich um langfristige Entwicklungen handelt. Ich sehe es als notwendigen Teil eines Kultur Lebenszyklus.\u2026","rel":"","context":"In &quot;Vision, Mission, Purpose, Why, Werte, Strategie, you Name it&quot;","block_context":{"text":"Vision, Mission, Purpose, Why, Werte, Strategie, you Name it","link":"https:\/\/qualitypush.com\/w\/category\/vision-mission-purpose-why-werte-strategie-you-name-it\/"},"img":{"alt_text":"","src":"","width":0,"height":0},"classes":[]},{"id":1703,"url":"https:\/\/qualitypush.com\/w\/2024\/10\/01\/4-felder-matrix-todos-sortieren-in-workshops\/","url_meta":{"origin":1001,"position":3},"title":"4 Felder Matrix: Todos sortieren in Workshops","author":"Patrick","date":"1. Oktober 2024","format":false,"excerpt":"Alles was 4 Felder hat, ist beliebt. Angefangen mit Eisenhowers dringlich vs. wichtig. \u00dcber BCGs I-Portfolio bis hin zu McKinseys, die haben nat\u00fcrlich neun Felder, is klar. In Workshops beliebt ist die \"Aufwand vs. Nutzen\" Matrix und heute soll es um genau diese gehen. Und ein bisschen um Eisenhower. Was\u2026","rel":"","context":"In &quot;Effizienz&quot;","block_context":{"text":"Effizienz","link":"https:\/\/qualitypush.com\/w\/category\/effizienz\/"},"img":{"alt_text":"","src":"https:\/\/i0.wp.com\/qualitypush.com\/w\/wp-content\/uploads\/2024\/10\/screenshot_20241001-0908177E24780219527471731768..jpg?resize=350%2C200&ssl=1","width":350,"height":200},"classes":[]},{"id":1087,"url":"https:\/\/qualitypush.com\/w\/2021\/03\/23\/serie-denkfehler-7-empathy-gap\/","url_meta":{"origin":1001,"position":4},"title":"Serie Denkfehler #8: Empathy Gap","author":"Patrick","date":"23. M\u00e4rz 2021","format":false,"excerpt":"\"Gechillte Leute haben keine Ahnung, wie es w\u00fctenden Leuten grade ergeht - und andersherum\" Wir sind mies darin, vorherzusagen, wie wir in einer ganz anderen Situation empfinden W\u00dcRDEN. Sind wir zum Beispiel gerade sehr w\u00fctend, k\u00f6nnen wir uns nicht pr\u00e4zise ausmalen, wie wir f\u00fchlen, denken und handeln w\u00fcrden, sobald wir\u2026","rel":"","context":"In &quot;Serie: Denkfehler im Job&quot;","block_context":{"text":"Serie: Denkfehler im Job","link":"https:\/\/qualitypush.com\/w\/category\/serie_denkfehler_im_job\/"},"img":{"alt_text":"","src":"https:\/\/i0.wp.com\/qualitypush.com\/w\/wp-content\/uploads\/2021\/03\/Screenshot_20210323-115205_SamsungNotes.jpg?resize=350%2C200&ssl=1","width":350,"height":200,"srcset":"https:\/\/i0.wp.com\/qualitypush.com\/w\/wp-content\/uploads\/2021\/03\/Screenshot_20210323-115205_SamsungNotes.jpg?resize=350%2C200&ssl=1 1x, https:\/\/i0.wp.com\/qualitypush.com\/w\/wp-content\/uploads\/2021\/03\/Screenshot_20210323-115205_SamsungNotes.jpg?resize=525%2C300&ssl=1 1.5x, https:\/\/i0.wp.com\/qualitypush.com\/w\/wp-content\/uploads\/2021\/03\/Screenshot_20210323-115205_SamsungNotes.jpg?resize=700%2C400&ssl=1 2x, https:\/\/i0.wp.com\/qualitypush.com\/w\/wp-content\/uploads\/2021\/03\/Screenshot_20210323-115205_SamsungNotes.jpg?resize=1050%2C600&ssl=1 3x"},"classes":[]},{"id":1805,"url":"https:\/\/qualitypush.com\/w\/2025\/06\/06\/2025-unterstuetzen-wir-las-sonadoras-in-ecuador\/","url_meta":{"origin":1001,"position":5},"title":"2025 unterst\u00fctzen wir Las So\u00f1adoras in Ecuador","author":"Patrick","date":"6. Juni 2025","format":false,"excerpt":"Seit einem Vortrag vor 20 engagierten Fu\u00dfballmanagerinnen aus aller Welt \u00fcber Change und Leadership unterst\u00fctze ich jedes Jahr ein Projekt. Letztes Jahr habe ich Jihan Alfindis Projekt W\u00eaplay unterst\u00fctzt, dieses Jahr geht's nach Ecuador zu Fernanda V\u00e1sconez an das Projekt Las So\u00f1adoras (Die Tr\u00e4umerinnen). Fernanda ist Gr\u00fcnderin und 'La Presidente'\u2026","rel":"","context":"In &quot;Vision, Mission, Purpose, Why, Werte, Strategie, you Name it&quot;","block_context":{"text":"Vision, Mission, Purpose, Why, Werte, Strategie, you Name it","link":"https:\/\/qualitypush.com\/w\/category\/vision-mission-purpose-why-werte-strategie-you-name-it\/"},"img":{"alt_text":"","src":"https:\/\/i0.wp.com\/qualitypush.com\/w\/wp-content\/uploads\/2025\/06\/img-20250603-wa0003826115769916322650.jpg?resize=350%2C200","width":350,"height":200,"srcset":"https:\/\/i0.wp.com\/qualitypush.com\/w\/wp-content\/uploads\/2025\/06\/img-20250603-wa0003826115769916322650.jpg?resize=350%2C200 1x, https:\/\/i0.wp.com\/qualitypush.com\/w\/wp-content\/uploads\/2025\/06\/img-20250603-wa0003826115769916322650.jpg?resize=525%2C300 1.5x, https:\/\/i0.wp.com\/qualitypush.com\/w\/wp-content\/uploads\/2025\/06\/img-20250603-wa0003826115769916322650.jpg?resize=700%2C400 2x, https:\/\/i0.wp.com\/qualitypush.com\/w\/wp-content\/uploads\/2025\/06\/img-20250603-wa0003826115769916322650.jpg?resize=1050%2C600 3x, https:\/\/i0.wp.com\/qualitypush.com\/w\/wp-content\/uploads\/2025\/06\/img-20250603-wa0003826115769916322650.jpg?resize=1400%2C800 4x"},"classes":[]}],"jetpack_sharing_enabled":true,"jetpack_likes_enabled":true,"_links":{"self":[{"href":"https:\/\/qualitypush.com\/w\/wp-json\/wp\/v2\/posts\/1001","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/qualitypush.com\/w\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/qualitypush.com\/w\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/qualitypush.com\/w\/wp-json\/wp\/v2\/users\/1"}],"replies":[{"embeddable":true,"href":"https:\/\/qualitypush.com\/w\/wp-json\/wp\/v2\/comments?post=1001"}],"version-history":[{"count":4,"href":"https:\/\/qualitypush.com\/w\/wp-json\/wp\/v2\/posts\/1001\/revisions"}],"predecessor-version":[{"id":1014,"href":"https:\/\/qualitypush.com\/w\/wp-json\/wp\/v2\/posts\/1001\/revisions\/1014"}],"wp:attachment":[{"href":"https:\/\/qualitypush.com\/w\/wp-json\/wp\/v2\/media?parent=1001"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/qualitypush.com\/w\/wp-json\/wp\/v2\/categories?post=1001"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/qualitypush.com\/w\/wp-json\/wp\/v2\/tags?post=1001"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}